{"id":117798,"date":"2019-04-11T07:00:33","date_gmt":"2019-04-11T11:00:33","guid":{"rendered":"\/home\/echoingwalls\/public_html\/blog\/wp-content\/uploads\/2019\/04mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report.jpg"},"modified":"2019-04-11T07:00:33","modified_gmt":"2019-04-11T11:00:33","slug":"mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2","status":"inherit","type":"attachment","link":"https:\/\/echoingwalls.com\/blog\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2\/","title":{"rendered":"Mel B settles defamation case with former nanny out of court for $2"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false},"class_list":["post-117798","attachment","type-attachment","status-inherit"],"amp_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-300x300.jpg 300w, https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-150x150.jpg 150w, https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div class=\"mh-excerpt\"><\/div>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":500,"height":500,"file":"2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report.jpg","sizes":{"thumbnail":{"file":"mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-150x150.jpg"},"medium":{"file":"mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-300x300.jpg"},"mh-magazine-lite-slider":{"file":"mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-500x438.jpg","width":500,"height":438,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-500x438.jpg"},"mh-magazine-lite-content":{"file":"mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-500x381.jpg","width":500,"height":381,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-500x381.jpg"},"mh-magazine-lite-medium":{"file":"mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-326x245.jpg"},"mh-magazine-lite-small":{"file":"mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report-80x60.jpg"},"full":{"file":"mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-06-25 15:50:28","thumbsOpt":0,"thumbsOptList":[],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"34.14"},"post":null,"source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/mel-b-settles-defamation-case-with-former-nanny-out-of-court-for-2-3-million-report.jpg","_links":{"self":[{"href":"https:\/\/echoingwalls.com\/blog\/wp-json\/wp\/v2\/media\/117798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/echoingwalls.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/echoingwalls.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"replies":[{"embeddable":true,"href":"https:\/\/echoingwalls.com\/blog\/wp-json\/wp\/v2\/comments?post=117798"}]}}