{"id":117824,"date":"2019-04-11T17:01:14","date_gmt":"2019-04-11T21:01:14","guid":{"rendered":"\/home\/echoingwalls\/public_html\/blog\/wp-content\/uploads\/2019\/04los-angeles-memorial-will-honor-rapper-nipsey-hussle.jpg"},"modified":"2019-04-11T17:01:14","modified_gmt":"2019-04-11T21:01:14","slug":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-4","status":"inherit","type":"attachment","link":"https:\/\/echoingwalls.com\/blog\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-4\/","title":{"rendered":"Los Angeles Memorial Will Honor Rapper Nipsey Hussle"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false},"class_list":["post-117824","attachment","type-attachment","status-inherit"],"amp_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-300x169.jpg 300w, https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-768x432.jpg 768w, https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-1024x576.jpg 1024w, https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-678x381.jpg 678w, https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle.jpg 1400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<div class=\"mh-excerpt\"><\/div>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1400,"height":787,"file":"2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle.jpg","sizes":{"thumbnail":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-150x150.jpg"},"medium":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-300x169.jpg"},"medium_large":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-768x432.jpg"},"large":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-1024x576.jpg"},"mh-magazine-lite-slider":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-1030x438.jpg","width":1030,"height":438,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-1030x438.jpg"},"mh-magazine-lite-content":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-678x381.jpg","width":678,"height":381,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-678x381.jpg"},"mh-magazine-lite-large":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-678x509.jpg","width":678,"height":509,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-678x509.jpg"},"mh-magazine-lite-medium":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-326x245.jpg","width":326,"height":245,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-326x245.jpg"},"mh-magazine-lite-small":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle-80x60.jpg"},"full":{"file":"los-angeles-memorial-will-honor-rapper-nipsey-hussle.jpg","width":1400,"height":787,"mime_type":"image\/jpeg","source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"npr_socialshare4","orientation":"0","keywords":[]},"ShortPixel":{"type":"lossy","exifKept":"0","date":"2019-06-25 15:48:10","thumbsOpt":0,"thumbsOptList":[],"excludeSizes":[],"retinasOpt":0},"ShortPixelImprovement":"85.15"},"post":null,"source_url":"https:\/\/echoingwalls.com\/blog\/wp-content\/uploads\/2019\/04\/los-angeles-memorial-will-honor-rapper-nipsey-hussle.jpg","_links":{"self":[{"href":"https:\/\/echoingwalls.com\/blog\/wp-json\/wp\/v2\/media\/117824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/echoingwalls.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/echoingwalls.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"replies":[{"embeddable":true,"href":"https:\/\/echoingwalls.com\/blog\/wp-json\/wp\/v2\/comments?post=117824"}]}}